{"id":3396,"date":"2022-10-12T14:41:00","date_gmt":"2022-10-12T17:41:00","guid":{"rendered":"https:\/\/estoyseguro.cl\/blog\/?p=3396"},"modified":"2023-04-19T12:30:17","modified_gmt":"2023-04-19T15:30:17","slug":"como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile","status":"publish","type":"post","link":"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/","title":{"rendered":"C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile"},"content":{"rendered":"\n<p>En Chile <strong>saber con la patente qui\u00e9n es el due\u00f1o de un auto<\/strong> es posible de diferentes maneras, todas muy sencillas. <\/p>\n\n\n\n<p>Este tr\u00e1mite te puede servir, por ejemplo, para <strong>verificar la identidad del due\u00f1o de un veh\u00edculo usado<\/strong> que pretendes comprar. Adem\u00e1s, con la patente tambi\u00e9n puedes acceder a otras informaciones de utilidad. Una de ellas es si es que tiene un <a href=\"https:\/\/estoyseguro.cl\/seguro-automotriz\/\">seguro automotriz<\/a>, que siempre es necesario para proteger de da\u00f1os a un autom\u00f3vil.<\/p>\n\n\n\n<section class=\"p-6 md:py-10 md:px-20 rounded-xl border-es-blue border-[2px] md:grid md:grid-cols-2 md:gap-6 hover:cursor-pointer hover:-translate-y-2 transition-all duration-500 ease-in\">\n    <div class=\"flex flex-col md:col-start-1 md:col-end-2\">\n        <a class=\"mb-6\" href=\"https:\/\/estoyseguro.cl\/seguro-automotriz\/\">\n            <h2 class=\"text-center md:text-left uppercase text-es-blue text-5xl\"><span class=\"text-red-800 font-extrabold\">Ahorra<\/span> <br>En tu <strong>Seguro de Auto<\/strong><\/h2>\n        <\/a>\n        <a class=\"bg-es-orange md:font-bold hover:bg-es-blue hover:-translate-y-2 transition-all duration-500 ease-in text-es-white px-8 py-2 rounded-xl mx-auto md:ml-0 text-center md:text-left uppercase text-lg\" href=\"https:\/\/estoyseguro.cl\/seguro-automotriz\/\">\u00a1Cotiza Gratis!<\/a>\n    <\/div>\n    <a class=\"block w-[100%] h-auto my-6 md:my-auto md:col-start-2 md:col-end-3\" href=\"https:\/\/estoyseguro.cl\/seguro-automotriz\/\">\n                            <img decoding=\"async\" loading=\"lazy\" load=\"lazy\" class=\"w-[90%] h-auto mx-auto\" width=\"90\" height=\"54\" src=\"https:\/\/estoyseguro.cl\/blog\/wp-content\/uploads\/2023\/03\/Auto-e1695672724353.png\" alt=\"seguro automotriz imagen\" \/>\n            <\/a>\n    <div class=\"md:col-start-1 md:col-end-3\">\n        <p class=\"text-center text-lg text-es-blue\">Recuerda siempre estar asegurado, te protegen a ti, a tu familia y a tu auto contra choques, robo, da\u00f1os y otros incidentes, incluyendo a terceros afectados en un accidente de tr\u00e1nsito.<\/p>\n    <\/div>\n<\/section>\n\n\n<p>A continuaci\u00f3n, revisa c\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en nuestro pa\u00eds.<\/p>\n\n\n\n<h2>El rol del Registro Civil<\/h2>\n\n\n\n<p>En nuestro pa\u00eds la base de datos correspondientes al padr\u00f3n electoral es manejado por el <strong>Registro Civil<\/strong>. Este incluye <strong>la patente, el n\u00famero de chasis y n\u00famero de motor <\/strong>de cada veh\u00edculo registrado.<\/p>\n\n\n\n<p>Un primer m\u00e9todo para conocer al due\u00f1o de un auto con la patente de esta es ingresar al sitio web del <a href=\"https:\/\/www.registrocivil.cl\/\" target=\"_blank\" rel=\"noreferrer noopener\">Registro Civil<\/a> -y en el apartado de Certificados en l\u00ednea buscar el <strong>&#8220;Certificado veh\u00edculo de anotaciones vigentes&#8221;<\/strong>. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"812\" height=\"249\" src=\"https:\/\/estoyseguro.cl\/blog\/wp-content\/uploads\/2022\/10\/image.png\" alt=\"\" class=\"wp-image-3397\" srcset=\"https:\/\/estoyseguro.cl\/blog\/wp-content\/uploads\/2022\/10\/image.png 812w, https:\/\/estoyseguro.cl\/blog\/wp-content\/uploads\/2022\/10\/image-768x236.png 768w\" sizes=\"(max-width: 812px) 100vw, 812px\" \/><figcaption class=\"wp-element-caption\">Sitio web del Registro Civil<\/figcaption><\/figure>\n\n\n\n<p>Para solicitarlo deber\u00e1s<strong> ingresar la patente que deseas y realizar un pago de solo $1.090<\/strong>. Si lo deseas, tambi\u00e9n puedes realizar esta solicitud de manera presencial en cualquier oficina del Registro Civil. <\/p>\n\n\n\n<h2>Plataformas gratuitas e informes pagados<\/h2>\n\n\n\n<p>Tambi\u00e9n existen otras alternativas para obtener la identificaci\u00f3n del due\u00f1o de un veh\u00edculo solo con su placa patente, incluso gratuitas. <\/p>\n\n\n\n<p>Entre ellas est\u00e1n los sitios web <a href=\"https:\/\/www.patentechile.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.patentechile.com<\/a> y <a href=\"https:\/\/www.volanteomaleta.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.volanteomaleta.com<\/a>, donde solo ingresando los n\u00fameros y letras que la componen <strong>podr\u00e1s acceder al nombre y rut de su due\u00f1o o due\u00f1a legal<\/strong>. Estos sitios web son de b\u00fasqueda gratuita, aunque existe la posibilidad de que, a diferencia del Registro Civil, los datos no se encuentren completamente actualizados. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1200\" height=\"800\" src=\"https:\/\/estoyseguro.cl\/blog\/wp-content\/uploads\/2022\/10\/2-3-1200x800.jpg\" alt=\"\" class=\"wp-image-3400\" srcset=\"https:\/\/estoyseguro.cl\/blog\/wp-content\/uploads\/2022\/10\/2-3-1200x800.jpg 1200w, https:\/\/estoyseguro.cl\/blog\/wp-content\/uploads\/2022\/10\/2-3-900x600.jpg 900w, https:\/\/estoyseguro.cl\/blog\/wp-content\/uploads\/2022\/10\/2-3-768x512.jpg 768w, https:\/\/estoyseguro.cl\/blog\/wp-content\/uploads\/2022\/10\/2-3.jpg 1260w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p>Otra opci\u00f3n es <strong>pagar por un informe automotriz <\/strong>que no solo da cuenta del due\u00f1o actual del veh\u00edculo, si no que presenta el historial de poseedores del auto, detalle de infracciones o multas, y antecedentes mec\u00e1nicos y legales, entre otros datos valiosos. <\/p>\n\n\n\n<p>Consultar los antecedentes e historial del veh\u00edculo es una de las <a href=\"https:\/\/estoyseguro.cl\/blog\/10-cosas-en-que-debes-fijarte-si-vas-a-comprar-un-auto-usado\/513\/\">10 recomendaciones sobre en qu\u00e9 fijarte si vas a comprar un auto usado<\/a>.<\/p>\n\n\n\n<p>Cabe recordar que <strong>en Chile la patente se utiliza para realizar cobros del TAG, cursar partes, e identificar veh\u00edculos que han sido robados<\/strong> o se han visto envuelto en accidentes.<\/p>\n\n\n\n<p>Si eres una persona quisquillosa, tambi\u00e9n te puede interesar saber <a href=\"https:\/\/estoyseguro.cl\/blog\/estos-son-los-10-modelos-de-auto-mas-robados-en-chile\/2717\/\">cuales son los 10 autos mas robados en Chile<\/a>, as\u00ed podr\u00e1s verificar su patente y asegurarte de no tener alg\u00fan problema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es un tr\u00e1mite que te puede servir, por ejemplo, para verificar la identidad del due\u00f1o antes de comprar un veh\u00edculo usado.<\/p>\n","protected":false},"author":9,"featured_media":3439,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[1],"tags":[19],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile<\/title>\n<meta name=\"description\" content=\"C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile: el tr\u00e1mite es sencillo y hay opciones gratuitas o de pago.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile\" \/>\n<meta property=\"og:description\" content=\"C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile: el tr\u00e1mite es sencillo y hay opciones gratuitas o de pago.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog EstoySeguro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Estoysegurochile\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-12T17:41:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-19T15:30:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/estoyseguro.cl\/blog\/wp-content\/uploads\/2022\/10\/saber-con-la-patente-quien-es-el-dueno-de-un-auto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"840\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/estoyseguro.cl\/blog\/#\/schema\/person\/3f88a8acb3e1463d133b6ebbe7a67c4e\"},\"headline\":\"C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile\",\"datePublished\":\"2022-10-12T17:41:00+00:00\",\"dateModified\":\"2023-04-19T15:30:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/\"},\"wordCount\":476,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/estoyseguro.cl\/blog\/#organization\"},\"keywords\":[\"Seguro Automotriz\"],\"articleSection\":[\"Art\u00edculos\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/\",\"url\":\"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/\",\"name\":\"C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile\",\"isPartOf\":{\"@id\":\"https:\/\/estoyseguro.cl\/blog\/#website\"},\"datePublished\":\"2022-10-12T17:41:00+00:00\",\"dateModified\":\"2023-04-19T15:30:17+00:00\",\"description\":\"C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile: el tr\u00e1mite es sencillo y hay opciones gratuitas o de pago.\",\"breadcrumb\":{\"@id\":\"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/estoyseguro.cl\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seguro Automotriz\",\"item\":\"https:\/\/estoyseguro.cl\/blog\/tag\/seguro-automotriz\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/estoyseguro.cl\/blog\/#website\",\"url\":\"https:\/\/estoyseguro.cl\/blog\/\",\"name\":\"Blog EstoySeguro\",\"description\":\"Todo lo que necesitas saber sobre el mundo de los seguros en un s\u00f3lo blog.\",\"publisher\":{\"@id\":\"https:\/\/estoyseguro.cl\/blog\/#organization\"},\"alternateName\":\"EstoySeguro\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/estoyseguro.cl\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/estoyseguro.cl\/blog\/#organization\",\"name\":\"EstoySeguro\",\"alternateName\":\"Blog EstoySeguro\",\"url\":\"https:\/\/estoyseguro.cl\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/estoyseguro.cl\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/estoyseguro.cl\/blog\/wp-content\/uploads\/2023\/10\/es-logo-footer.svg\",\"contentUrl\":\"https:\/\/estoyseguro.cl\/blog\/wp-content\/uploads\/2023\/10\/es-logo-footer.svg\",\"width\":\"1200\",\"height\":\"800\",\"caption\":\"EstoySeguro\"},\"image\":{\"@id\":\"https:\/\/estoyseguro.cl\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Estoysegurochile\/\",\"https:\/\/www.linkedin.com\/company\/estoysegurocl\/\",\"https:\/\/www.instagram.com\/estoysegurocl\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/estoyseguro.cl\/blog\/#\/schema\/person\/3f88a8acb3e1463d133b6ebbe7a67c4e\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/estoyseguro.cl\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0ac092d529d0b698dd07e7b3d51f9107?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0ac092d529d0b698dd07e7b3d51f9107?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\/\/estoyseguro.cl\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile","description":"C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile: el tr\u00e1mite es sencillo y hay opciones gratuitas o de pago.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile","og_description":"C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile: el tr\u00e1mite es sencillo y hay opciones gratuitas o de pago.","og_url":"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/","og_site_name":"Blog EstoySeguro","article_publisher":"https:\/\/www.facebook.com\/Estoysegurochile\/","article_published_time":"2022-10-12T17:41:00+00:00","article_modified_time":"2023-04-19T15:30:17+00:00","og_image":[{"width":1600,"height":840,"url":"https:\/\/estoyseguro.cl\/blog\/wp-content\/uploads\/2022\/10\/saber-con-la-patente-quien-es-el-dueno-de-un-auto.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/#article","isPartOf":{"@id":"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/"},"author":{"name":"admin","@id":"https:\/\/estoyseguro.cl\/blog\/#\/schema\/person\/3f88a8acb3e1463d133b6ebbe7a67c4e"},"headline":"C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile","datePublished":"2022-10-12T17:41:00+00:00","dateModified":"2023-04-19T15:30:17+00:00","mainEntityOfPage":{"@id":"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/"},"wordCount":476,"commentCount":0,"publisher":{"@id":"https:\/\/estoyseguro.cl\/blog\/#organization"},"keywords":["Seguro Automotriz"],"articleSection":["Art\u00edculos"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/","url":"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/","name":"C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile","isPartOf":{"@id":"https:\/\/estoyseguro.cl\/blog\/#website"},"datePublished":"2022-10-12T17:41:00+00:00","dateModified":"2023-04-19T15:30:17+00:00","description":"C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile: el tr\u00e1mite es sencillo y hay opciones gratuitas o de pago.","breadcrumb":{"@id":"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/estoyseguro.cl\/blog\/como-saber-con-la-patente-quien-es-el-dueno-de-un-auto-en-chile\/3396\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/estoyseguro.cl\/blog\/"},{"@type":"ListItem","position":2,"name":"Seguro Automotriz","item":"https:\/\/estoyseguro.cl\/blog\/tag\/seguro-automotriz\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo saber con la patente qui\u00e9n es el due\u00f1o de un auto en Chile"}]},{"@type":"WebSite","@id":"https:\/\/estoyseguro.cl\/blog\/#website","url":"https:\/\/estoyseguro.cl\/blog\/","name":"Blog EstoySeguro","description":"Todo lo que necesitas saber sobre el mundo de los seguros en un s\u00f3lo blog.","publisher":{"@id":"https:\/\/estoyseguro.cl\/blog\/#organization"},"alternateName":"EstoySeguro","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/estoyseguro.cl\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/estoyseguro.cl\/blog\/#organization","name":"EstoySeguro","alternateName":"Blog EstoySeguro","url":"https:\/\/estoyseguro.cl\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/estoyseguro.cl\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/estoyseguro.cl\/blog\/wp-content\/uploads\/2023\/10\/es-logo-footer.svg","contentUrl":"https:\/\/estoyseguro.cl\/blog\/wp-content\/uploads\/2023\/10\/es-logo-footer.svg","width":"1200","height":"800","caption":"EstoySeguro"},"image":{"@id":"https:\/\/estoyseguro.cl\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Estoysegurochile\/","https:\/\/www.linkedin.com\/company\/estoysegurocl\/","https:\/\/www.instagram.com\/estoysegurocl\/"]},{"@type":"Person","@id":"https:\/\/estoyseguro.cl\/blog\/#\/schema\/person\/3f88a8acb3e1463d133b6ebbe7a67c4e","name":"admin","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/estoyseguro.cl\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0ac092d529d0b698dd07e7b3d51f9107?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0ac092d529d0b698dd07e7b3d51f9107?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/estoyseguro.cl\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/estoyseguro.cl\/blog\/wp-json\/wp\/v2\/posts\/3396"}],"collection":[{"href":"https:\/\/estoyseguro.cl\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/estoyseguro.cl\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/estoyseguro.cl\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/estoyseguro.cl\/blog\/wp-json\/wp\/v2\/comments?post=3396"}],"version-history":[{"count":6,"href":"https:\/\/estoyseguro.cl\/blog\/wp-json\/wp\/v2\/posts\/3396\/revisions"}],"predecessor-version":[{"id":3970,"href":"https:\/\/estoyseguro.cl\/blog\/wp-json\/wp\/v2\/posts\/3396\/revisions\/3970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/estoyseguro.cl\/blog\/wp-json\/wp\/v2\/media\/3439"}],"wp:attachment":[{"href":"https:\/\/estoyseguro.cl\/blog\/wp-json\/wp\/v2\/media?parent=3396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/estoyseguro.cl\/blog\/wp-json\/wp\/v2\/categories?post=3396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/estoyseguro.cl\/blog\/wp-json\/wp\/v2\/tags?post=3396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}